{"id":11972,"date":"2021-03-15T12:45:19","date_gmt":"2021-03-15T11:45:19","guid":{"rendered":"https:\/\/cronacabianca.certhidea.it\/tv\/?post_type=video&#038;p=11972"},"modified":"2021-03-15T12:48:07","modified_gmt":"2021-03-15T11:48:07","slug":"question-time-con-giancarlo-tagliaferri-04-03-2021-2","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/question-time-con-giancarlo-tagliaferri-04-03-2021-2\/","title":{"rendered":"Question time con Katia Tarasconi 08\/03\/2021"},"content":{"rendered":"<p>L&#8217;Italia \u00e8 tredicesima in Europa per percentuale di donne ministro e sotto la media europea del 30%. Anche per questo, con <strong>Katia Tarasconi<\/strong> del <strong>Partito democratico<\/strong> abbiamo voluto parlare di rappresentanza femminile in politica, in questa puntata del podcast che esce nella giornata dell&#8217;8 marzo e della Giornata internazionale della donna. Tra quote rose, ruolo delle donne nelle istituzioni e all&#8217;interno del Pd, fino all&#8217;elezione negli States di Kamala Harris, prima vicepresidente donna, afroamericana e di origini asiatiche&#8230;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":12,"featured_media":11971,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[346,820],"video-tag":[],"class_list":["post-11972","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-programmi-audio","categories-podcast"],"senape_tv_rid":"","senape_tv_type":"","media_type":"","codice_da_embeddare":"","pubblica_in_testata_cronacabianca":[],"titolo_per_testata_cronacabianca":"","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/11972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=11972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/11971"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=11972"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=11972"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=11972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}