{"id":12709,"date":"2023-07-27T12:06:22","date_gmt":"2023-07-27T10:06:22","guid":{"rendered":"https:\/\/cronacabianca.certhidea.it\/tv\/?post_type=video&#038;p=12709"},"modified":"2023-07-27T12:06:22","modified_gmt":"2023-07-27T10:06:22","slug":"assemblea-on-er-puntata-50-28-07-2023-2","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/assemblea-on-er-puntata-50-28-07-2023-2\/","title":{"rendered":"Assemblea On Er, puntata 50 \u2013 28\/07\/2023"},"content":{"rendered":"<p>La manovra di assestamento del bilancio regionale e i commenti delle forze politiche, le iniziative delle commissioni assembleari per l\u2019emergenza post alluvione, la nuova legge sulle reti elettriche e la liberazione di Patrick Zaki.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":12,"featured_media":12710,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[822,345],"video-tag":[],"class_list":["post-12709","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-on-er-tv","categories-programmi-video"],"senape_tv_rid":"","senape_tv_type":"","media_type":"","codice_da_embeddare":"","pubblica_in_testata_cronacabianca":"1","titolo_per_testata_cronacabianca":"La manovra di bilancio e la visita delle Commissioni nelle zone alluvionate in questa puntata OnEr","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/12709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=12709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/12710"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=12709"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=12709"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=12709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}