{"id":12812,"date":"2024-03-19T11:26:25","date_gmt":"2024-03-19T10:26:25","guid":{"rendered":"https:\/\/cronacabianca.certhidea.it\/tv\/?post_type=video&#038;p=12812"},"modified":"2024-03-19T11:26:25","modified_gmt":"2024-03-19T10:26:25","slug":"consiglio-darte-in-too-deep-dalla-rete-allintelligenza-artificiale","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/consiglio-darte-in-too-deep-dalla-rete-allintelligenza-artificiale\/","title":{"rendered":"Consiglio d&#8217;Arte &#8211; In too deep &#8211; Dalla rete all&#8217;intelligenza artificiale"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/widget.spreaker.com\/player?episode_id=58306318&amp;theme=light&amp;playlist=false&amp;playlist-continuous=false&amp;chapters-image=true&amp;episode_image_position=right&amp;hide-logo=false&amp;hide-likes=false&amp;hide-comments=false&amp;hide-sharing=false&amp;hide-download=true\" width=\"100%\" height=\"200px\" frameborder=\"0\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p>Una mostra nata da una serie di prompts, ovvero da frasi lanciate sul web, e da un lavoro di stratificazione di materiali diversi: come la rete e il tulle. \u00c8 &#8220;In <b>Too deep &#8211; Dalla rete all&#8217;intelligenza artificiale<\/b>&#8220;, dell&#8217;artista <b>Giorgio Tentolini <\/b>che gioca con le nuove tecniche del web al servizio dell&#8217;arte. Come ha fatto lo spiega nel podcast ripercorrendo le sue opere pi\u00f9 significative, &#8220;No One&#8221;, &#8220;Algor&#8221;, nate proprio grazie alla tecnica dell&#8217;intelligenza artificiale, usata per ricreare volti di donne e uomini, esteticamente perfetti, tagliando &#8220;materiali semplici&#8221; come spiega l&#8217;artista. Social, intelligenza artificiale, arte greca, sensualit\u00e0, perfezione e sospensione: sono i temi affrontati nelle opere di Tentolini. Nel podcast il suo racconto.<\/p>\n<p><i>Seguendo la suddivisione in capitoli (su Spreaker) \u00e8 anche possibile visionare le opere di cui l&#8217;artista parla e ingrandirle cliccando sul link.<\/i><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":9,"featured_media":12813,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[346,820],"video-tag":[],"class_list":["post-12812","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-programmi-audio","categories-podcast"],"senape_tv_rid":"","senape_tv_type":"","media_type":"","codice_da_embeddare":"","pubblica_in_testata_cronacabianca":"0","titolo_per_testata_cronacabianca":"","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/12812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=12812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/12813"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=12812"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=12812"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=12812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}