{"id":12832,"date":"2024-03-27T10:02:20","date_gmt":"2024-03-27T09:02:20","guid":{"rendered":"https:\/\/cronacabianca.certhidea.it\/tv\/?post_type=video&#038;p=12832"},"modified":"2024-03-28T14:57:11","modified_gmt":"2024-03-28T13:57:11","slug":"le-torri-di-kenzo-tange-per-le-giornate-fai-di-primavera-un-pezzo-di-politica-arte-e-storia-di-bologna","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/le-torri-di-kenzo-tange-per-le-giornate-fai-di-primavera-un-pezzo-di-politica-arte-e-storia-di-bologna\/","title":{"rendered":"Le Torri di Kenzo Tange per le Giornate Fai di Primavera: un pezzo di politica, arte e storia di Bologna"},"content":{"rendered":"<p>La Torre di Kenzo Tange di Bologna, quella dell&#8217;Assemblea legislativa, \u00e8 stata scelta come meta delle Giornate Fai di Primavera. Il perch\u00e9 della scelta, i commenti delle guide Fai, degli studenti \u2018ciceroni\u2019 del Liceo Da Vinci di Casalecchio di Reno, i visitatori che hanno espresso le loro preferenze e tutti i segreti di un luogo di Bologna fuori dalle classiche rotte turistiche.<\/p>\n<p>(27 marzo 2024)<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":9,"featured_media":12833,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[346,823],"video-tag":[],"class_list":["post-12832","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-programmi-audio","categories-on-er-radio"],"senape_tv_rid":"","senape_tv_type":"","media_type":"","codice_da_embeddare":"<iframe src=\"https:\/\/widget.spreaker.com\/player?episode_id=59178970&amp;theme=light&amp;playlist=false&amp;playlist-continuous=false&amp;chapters-image=true&amp;episode_image_position=right&amp;hide-logo=false&amp;hide-likes=false&amp;hide-comments=false&amp;hide-sharing=false&amp;hide-download=true\" width=\"100%\" height=\"200px\" frameborder=\"0\"><\/iframe>","pubblica_in_testata_cronacabianca":"1","titolo_per_testata_cronacabianca":"ON ER: le Torri di Kenzo Tange per le Giornate Fai","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/12832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=12832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/12833"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=12832"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=12832"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=12832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}