{"id":13079,"date":"2025-02-26T13:50:24","date_gmt":"2025-02-26T12:50:24","guid":{"rendered":"https:\/\/cronacabianca.certhidea.it\/tv\/?post_type=video&#038;p=13079"},"modified":"2025-02-26T17:42:01","modified_gmt":"2025-02-26T16:42:01","slug":"on-er-autonomia-differenziata-e-il-contest-di-calcolo-al-tecnopolo","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/on-er-autonomia-differenziata-e-il-contest-di-calcolo-al-tecnopolo\/","title":{"rendered":"On ER: autonomia differenziata e il contest di calcolo al Tecnopolo"},"content":{"rendered":"<p>Il contest di calcolo ad alte prestazioni rivolto ai ragazzi delle scuole, la risoluzione \u201cSafe Place for Women\u201d e l\u2019autonomia differenziata: sono gli argomenti al centro della nuova puntata di\u00a0<strong>On ER, il giornale dell\u2019Emilia-Romagna<\/strong>. Il contest organizzato da Assemblea legislativa e Cineca si chiama \u2018Usando Leonardo\u2019 e ha lo scopo di diffondere le competenze digitali nel mondo della scuola. L\u2019evento ha coinvolto una trentina di studenti delle superiori, impegnati in una competizione per la costruzione di un complicatissimo codice informatico, e tutto grazie all\u2019aiuto del supercomputer Leonardo. A vincere il contest, l\u2019ITT Pascal di Cesena, premiati con un buono libri del valore di 500 euro.<\/p>\n<p>In Assemblea si \u00e8 tenuta anche la seduta del consiglio regionale. Sono stati diversi i temi all\u2019ordine del giorno. A partire da \u201cSafe Place for Women\u201d, una risoluzione a prima firma di Marcella Zappaterra del Partito democratico e poi approvata dall\u2019Assemblea con i voti del centrosinistra. Un progetto lanciato dal Gruppo dei Socialisti &amp; Democratici Europei e rivolto al Comitato delle Regioni. L\u2019obiettivo \u00e8\u00a0 quello di promuovere politiche concrete per rendere le citt\u00e0 luoghi pi\u00f9 sicuri contro la violenza di genere. Ma l\u2019argomento principale affrontato dal consiglio regionale \u00e8 stato quello dell\u2019autonomia differenziata. Il Presidente de Pascale ha annunciato il ritiro della proposta avanzata dalla Regione nel 2017.<\/p>\n<p>Anche il lavoro delle commissioni procede spedito. L\u2019assessore alla Sanit\u00e0 Massimo Fabi ha incontrato i consiglieri per illustrare le sue linee di mandato. Ha parlato di modernizzare il sistema ospedaliero, di investire sul capitale umano e su quello professionale, potenziando la ricerca e lo sviluppo dell\u2019assistenza sociosanitaria.<\/p>\n<p>I consiglieri intervistati nei servizi sono: Paolo Calvano, Giovanni Gordini, Marta Evangelisti, Tommaso Fiazza, Paolo Trande, Lorenzo Casadei, Marco Mastacchi, Andrea Massari, Francesco Sassone, Raffaele Donini, Valentina Castaldini.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":9,"featured_media":13081,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[822,345],"video-tag":[],"class_list":["post-13079","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-on-er-tv","categories-programmi-video"],"senape_tv_rid":"","senape_tv_type":"","media_type":"","codice_da_embeddare":"","pubblica_in_testata_cronacabianca":"1","titolo_per_testata_cronacabianca":"","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/13079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=13079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/13081"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=13079"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=13079"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=13079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}