{"id":13101,"date":"2025-03-07T15:32:37","date_gmt":"2025-03-07T14:32:37","guid":{"rendered":"https:\/\/cronacabianca.certhidea.it\/tv\/?post_type=video&#038;p=13101"},"modified":"2025-03-07T16:37:46","modified_gmt":"2025-03-07T15:37:46","slug":"8-marzo-il-presidente-maurizio-fabbri-troppe-diseguaglianze-dobbiamo-ancora-lottare","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/8-marzo-il-presidente-maurizio-fabbri-troppe-diseguaglianze-dobbiamo-ancora-lottare\/","title":{"rendered":"8 marzo, il presidente Maurizio Fabbri: \u201cTroppe diseguaglianze, dobbiamo ancora lottare\u201d"},"content":{"rendered":"<p>&#8220;L&#8217;8 marzo \u00e8 un momento importante per riflettere su quello che \u00e8 stato fatto fino a oggi, le tante battaglie che hanno portato nuovi diritti, nuove libert\u00e0 e un nuovo ruolo della donna all&#8217;interno della nostra societ\u00e0. Ma \u00e8 anche un momento per riflettere su quello che possiamo ancora fare, sulle battaglie che dobbiamo ancora intraprendere. Io credo che uno degli obiettivi principali sia quello di concentrarsi sulle politiche della formazione e del lavoro, perch\u00e9 oggi in Italia ci sono ancora otto milioni di donne non occupate&#8221;.<\/p>\n<p>Cos\u00ec il presidente dell&#8217;Assemblea legislativa della Regione Emilia-Romagna <strong>Maurizio Fabbri<\/strong> in occasione dell&#8217;8 marzo, Giornata internazionale della donna.<\/p>\n<p>&#8220;Siamo all&#8217;ultimo posto nelle classifiche europee. In Emilia-Romagna andiamo meglio, ma anche qui c&#8217;\u00e8 ancora tanto da fare. Abbiamo l&#8217;indice di occupazione che \u00e8 al 60%,mentre la media europea \u00e8 al 70%. Quindi -sottolinea Fabbri- ci sono ancora margini e noi dobbiamo cercare di coprirli tutti e di impegnarci ancora di pi\u00f9 in un mondo che cambia velocemente. Credo che il ruolo della donna, come quello di ogni cittadino, sia in continua evoluzione e noi dobbiamo anticipare questi tempi, anche perch\u00e9 il lavoro \u00e8 ancora il principale motore di ascensore sociale, di emancipazione e di sicurezza economica e non solo: le nostre battaglie dovranno essere ancora pi\u00f9 forti, ancora pi\u00f9 efficaci e soprattutto innovative per stare al passo con i tempi&#8221;.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":12,"featured_media":13104,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[798,345],"video-tag":[],"class_list":["post-13101","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-eventi","categories-programmi-video"],"senape_tv_rid":"","senape_tv_type":"","media_type":"","codice_da_embeddare":"","pubblica_in_testata_cronacabianca":"1","titolo_per_testata_cronacabianca":"8 marzo, il presidente Maurizio Fabbri: \u201cTroppe diseguaglianze, dobbiamo ancora lottare\u201d","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/13101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=13101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/13104"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=13101"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=13101"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=13101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}