{"id":13134,"date":"2025-03-25T16:09:35","date_gmt":"2025-03-25T15:09:35","guid":{"rendered":"https:\/\/cronacabianca.certhidea.it\/tv\/?post_type=video&#038;p=13134"},"modified":"2025-03-27T10:11:29","modified_gmt":"2025-03-27T09:11:29","slug":"bullismo-e-disagio-adolescenziale-lintervista-alla-garante-claudia-giudici","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/bullismo-e-disagio-adolescenziale-lintervista-alla-garante-claudia-giudici\/","title":{"rendered":"Bullismo e disagio adolescenziale: l\u2019intervista alla garante Claudia Giudici"},"content":{"rendered":"<p>Ne parlano le serie tv; ne parlano troppo spesso i giornali; \u00e8 un tema ancora troppo attuale: il bullismo fra i ragazzi. E quando si parla di questo argomento viene facile parlare anche dei social e dell\u2019utilizzo che ne fanno i ragazzi. E di bullismo che si trasforma troppe volte in cyberbullismo. Di questi temi, ma anche del malessere giovanile, del disagio che i ragazzi, in particolare adolescenti, vivono oggi, ha parlato la garante regionale per l\u2019Infanzia e l\u2019adolescenza Claudia Giudici, ospite di\u00a0<strong>On ER, il giornale dell\u2019Emilia-Romagna<\/strong>.<\/p>\n<p>Ma non \u00e8 mancata la politica, nell\u2019ultima puntata di On ER: la commissione Sanit\u00e0 ha discusso il tema del fine vita. La richiesta che arriva \u00e8 quella di avere una legge nazionale, uguale per tutte le regioni. Invece, in commissione Politiche economiche, il vicepresidente dell\u2019Emilia-Romagna Vincenzo Colla ha presentato il programma di lavoro dei prossimi anni in tema di sviluppo economico e politiche energetiche. In commissione Territorio l\u2019assessore al Bilancio Davide Baruffi ha confermato gli investimenti per le aree pi\u00f9 colpite dall\u2019alluvione del 2023 e del 2024, mentre l\u2019assessora Gessica Allegni ha presentato gli obiettivi di mandato sui parchi dell\u2019Emilia-Romagna. Fra le linee guida \u00e8 previsto il raggiungimento dei target europei per le aree protette, la creazione del Parco nazionale del Delta del Po oltre a una maggiore valorizzazione del patrimonio forestale.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":12,"featured_media":13133,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[822,345],"video-tag":[],"class_list":["post-13134","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-on-er-tv","categories-programmi-video"],"senape_tv_rid":"","senape_tv_type":"","media_type":"","codice_da_embeddare":"","pubblica_in_testata_cronacabianca":"1","titolo_per_testata_cronacabianca":"On ER: bullismo e disagio adolescenziale, l\u2019intervista alla garante Claudia Giudici","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/13134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=13134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/13133"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=13134"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=13134"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=13134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}