{"id":5228,"date":"2016-12-15T00:00:00","date_gmt":"2016-12-14T23:00:00","guid":{"rendered":"http:\/\/cronacabianca.eu\/tv\/video\/islam-in-emilia-romagna-luoghi-di-culto-o-di-cultura\/"},"modified":"2018-11-14T17:08:15","modified_gmt":"2018-11-14T16:08:15","slug":"islam-in-emilia-romagna-luoghi-di-culto-o-di-cultura","status":"publish","type":"video","link":"https:\/\/cronacabianca.eu\/tv\/video\/islam-in-emilia-romagna-luoghi-di-culto-o-di-cultura\/","title":{"rendered":"Islam in Emilia-Romagna: luoghi di culto o di cultura?"},"content":{"rendered":"<p>Approfondimento sulla\u00a0<strong>prima mappatura dei luoghi di culto islamici in Emilia-Romagna<\/strong><em>,\u00a0<\/em>ricerca curata\u00a0dall\u2019Osservatorio per il pluralismo religioso e dal Gris\u00a0(gruppo di ricerca e informazione socio religiosa). Oltre a presentare\u00a0i dati in Emilia-Romagna la ricerca si\u00a0concentra sull\u2019analisi delle diverse tendenze culturali dei vari luoghi di culto. Nel video gli interventi di <strong>Yassin Lafram<\/strong>, coordinatore della comunit\u00e0 islamica di Bologna e <strong>Pino Luc\u00e0 Trombetta<\/strong> dell&#8217;Osservatorio sul pluralismo religioso.<\/p>\n<p><strong>Per saperne di pi\u00f9<\/strong>: <a href=\"http:\/\/cronacabianca.eu\/in-assemblea-domani-si-presenta-la-prima-geomappa-dei-luoghi-di-culto-islamici-invito\/\">leggi la notizia\u00a0<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"author":27,"featured_media":10914,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","video-category":[798,345],"video-tag":[815],"class_list":["post-5228","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categories-eventi","categories-programmi-video","video_tag-eventi"],"senape_tv_rid":"RURSZT3LSL7Q","senape_tv_type":"Video","media_type":"","codice_da_embeddare":"","pubblica_in_testata_cronacabianca":[],"titolo_per_testata_cronacabianca":"","_links":{"self":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video\/5228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/comments?post=5228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media\/10914"}],"wp:attachment":[{"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/media?parent=5228"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-category?post=5228"},{"taxonomy":"video_tag","embeddable":true,"href":"https:\/\/cronacabianca.eu\/tv\/wp-json\/wp\/v2\/video-tag?post=5228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}